{"id":6370,"count":170,"description":"","link":"https:\/\/denhelder.online\/en\/category\/evenementen\/evenement\/","name":"Event","slug":"event-2","taxonomy":"category","parent":6365,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Evenement - Den Helder Online<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evenement Archieven\" \/>\n<meta property=\"og:url\" content=\"https:\/\/denhelder.online\/en\/category\/events\/event-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Den Helder Online\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/denhelder.online\\\/category\\\/evenementen\\\/evenement\\\/\",\"url\":\"https:\\\/\\\/denhelder.online\\\/category\\\/evenementen\\\/evenement\\\/\",\"name\":\"Evenement - Den Helder Online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/denhelder.online\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/denhelder.online\\\/category\\\/evenementen\\\/evenement\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/denhelder.online\\\/category\\\/evenementen\\\/evenement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/denhelder.online\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evenementen\",\"item\":\"https:\\\/\\\/denhelder.online\\\/category\\\/evenementen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Evenement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/denhelder.online\\\/#website\",\"url\":\"https:\\\/\\\/denhelder.online\\\/\",\"name\":\"Den Helder Online\",\"description\":\"Beleef Den Helder\",\"publisher\":{\"@id\":\"https:\\\/\\\/denhelder.online\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/denhelder.online\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/denhelder.online\\\/#organization\",\"name\":\"Den Helder Online\",\"url\":\"https:\\\/\\\/denhelder.online\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/denhelder.online\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/denhelder.online\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/DitIsDH-Logo-26-tagline.svg\",\"contentUrl\":\"https:\\\/\\\/denhelder.online\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/DitIsDH-Logo-26-tagline.svg\",\"width\":1717.1,\"height\":934.9,\"caption\":\"Den Helder Online\"},\"image\":{\"@id\":\"https:\\\/\\\/denhelder.online\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Evenement - Den Helder Online","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Evenement Archieven","og_url":"https:\/\/denhelder.online\/en\/category\/events\/event-2\/","og_site_name":"Den Helder Online","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/denhelder.online\/category\/evenementen\/evenement\/","url":"https:\/\/denhelder.online\/category\/evenementen\/evenement\/","name":"Event - Den Helder Online","isPartOf":{"@id":"https:\/\/denhelder.online\/#website"},"breadcrumb":{"@id":"https:\/\/denhelder.online\/category\/evenementen\/evenement\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/denhelder.online\/category\/evenementen\/evenement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/denhelder.online\/"},{"@type":"ListItem","position":2,"name":"Evenementen","item":"https:\/\/denhelder.online\/category\/evenementen\/"},{"@type":"ListItem","position":3,"name":"Evenement"}]},{"@type":"WebSite","@id":"https:\/\/denhelder.online\/#website","url":"https:\/\/denhelder.online\/","name":"Den Helder Online","description":"Experience Den Helder","publisher":{"@id":"https:\/\/denhelder.online\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/denhelder.online\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/denhelder.online\/#organization","name":"Den Helder Online","url":"https:\/\/denhelder.online\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/denhelder.online\/#\/schema\/logo\/image\/","url":"https:\/\/denhelder.online\/wp-content\/uploads\/2021\/12\/DitIsDH-Logo-26-tagline.svg","contentUrl":"https:\/\/denhelder.online\/wp-content\/uploads\/2021\/12\/DitIsDH-Logo-26-tagline.svg","width":1717.1,"height":934.9,"caption":"Den Helder Online"},"image":{"@id":"https:\/\/denhelder.online\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/denhelder.online\/en\/wp-json\/wp\/v2\/categories\/6370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/denhelder.online\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/denhelder.online\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/denhelder.online\/en\/wp-json\/wp\/v2\/categories\/6365"}],"wp:post_type":[{"href":"https:\/\/denhelder.online\/en\/wp-json\/wp\/v2\/posts?categories=6370"},{"href":"https:\/\/denhelder.online\/en\/wp-json\/wp\/v2\/events?categories=6370"},{"href":"https:\/\/denhelder.online\/en\/wp-json\/wp\/v2\/locations?categories=6370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}